{"id":2378,"date":"2013-11-10T04:02:41","date_gmt":"2013-11-10T04:02:41","guid":{"rendered":"http:\/\/biomediaproject.com\/bmp\/?page_id=2378"},"modified":"2021-02-23T23:46:23","modified_gmt":"2021-02-23T23:46:23","slug":"takanuva-feral","status":"publish","type":"page","link":"https:\/\/biomediaproject.com\/bmp\/pictures\/site\/wallpaper\/y2003\/takanuva-feral\/","title":{"rendered":"Takanuva"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-2378 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2013\/11\/1024x7687.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2013\/11\/1024x7687-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-5723\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-5723'>\n\t\t\t\t1024&#215;768\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2013\/11\/1280x10244.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2013\/11\/1280x10244-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-5724\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-5724'>\n\t\t\t\t1024&#215;768\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2013\/11\/1600x12003.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2013\/11\/1600x12003-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-5725\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-5725'>\n\t\t\t\t1600&#215;1200\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2013\/11\/1920x108028.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2013\/11\/1920x108028-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-5726\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-5726'>\n\t\t\t\t1920&#215;1080\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<div id='gallery-2' class='gallery galleryid-2378 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/pictures\/site\/wallpaper\/y2003\/takanuva-feral\/1600x1200cover\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2021\/02\/1600x1200cover-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-19426\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-19426'>\n\t\t\t\t1600&#215;1200\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":19331,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2378","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/2378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/comments?post=2378"}],"version-history":[{"count":4,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/2378\/revisions"}],"predecessor-version":[{"id":19427,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/2378\/revisions\/19427"}],"up":[{"embeddable":true,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/19331"}],"wp:attachment":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/media?parent=2378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}