{"id":13858,"date":"2020-12-18T01:41:13","date_gmt":"2020-12-18T01:41:13","guid":{"rendered":"http:\/\/biomediaproject.com\/bmp\/?page_id=13858"},"modified":"2020-12-18T01:41:17","modified_gmt":"2020-12-18T01:41:17","slug":"axalara-t9","status":"publish","type":"page","link":"https:\/\/biomediaproject.com\/bmp\/pictures\/advance-art\/y2008\/sets\/vehicles\/axalara-t9\/","title":{"rendered":"Axalara T9"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-13858 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-Wallpaper-Dark.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-Wallpaper-Dark-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-Wallpaper-Dark-300x225.jpg 300w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-Wallpaper-Dark-1024x768.jpg 1024w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-Wallpaper-Dark-768x576.jpg 768w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-Wallpaper-Dark.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-02-Big-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"188\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-02-Big-300x188.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-02-Big-300x188.jpg 300w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-02-Big-1024x640.jpg 1024w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-02-Big-768x480.jpg 768w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-02-Big-1536x961.jpg 1536w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-02-Big-2048x1281.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-03.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"204\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-03-300x204.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-03-300x204.jpg 300w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Axalara-T9-03.jpg 560w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Lewa.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"204\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Lewa-300x204.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Lewa-300x204.jpg 300w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Lewa.jpg 560w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":551,"featured_media":0,"parent":13856,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13858","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/13858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/users\/551"}],"replies":[{"embeddable":true,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/comments?post=13858"}],"version-history":[{"count":1,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/13858\/revisions"}],"predecessor-version":[{"id":13863,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/13858\/revisions\/13863"}],"up":[{"embeddable":true,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/13856"}],"wp:attachment":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/media?parent=13858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}