{"id":13584,"date":"2020-12-17T17:56:13","date_gmt":"2020-12-17T17:56:13","guid":{"rendered":"http:\/\/biomediaproject.com\/bmp\/?page_id=13584"},"modified":"2020-12-17T17:56:13","modified_gmt":"2020-12-17T17:56:13","slug":"toa-undersea-attack","status":"publish","type":"page","link":"https:\/\/biomediaproject.com\/bmp\/pictures\/advance-art\/y2007\/sets\/playsets\/toa-undersea-attack\/","title":{"rendered":"Toa Undersea Attack"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-13584 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Toa-Undersea-Attack-bioniclestory.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"214\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Toa-Undersea-Attack-bioniclestory-300x214.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Toa-Undersea-Attack-bioniclestory-300x214.jpg 300w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Toa-Undersea-Attack-bioniclestory.jpg 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Toa-Undersea-Attack-Wallpaper.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Toa-Undersea-Attack-Wallpaper-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Toa-Undersea-Attack-Wallpaper-300x225.jpg 300w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Toa-Undersea-Attack-Wallpaper-1024x768.jpg 1024w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Toa-Undersea-Attack-Wallpaper-768x576.jpg 768w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Toa-Undersea-Attack-Wallpaper-1536x1152.jpg 1536w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Toa-Undersea-Attack-Wallpaper.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Set_Rahi_Stinger_Whale.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Set_Rahi_Stinger_Whale-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Set_Rahi_Stinger_Whale-300x225.jpg 300w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Set_Rahi_Stinger_Whale-1024x767.jpg 1024w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Set_Rahi_Stinger_Whale-768x575.jpg 768w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Set_Rahi_Stinger_Whale-1536x1150.jpg 1536w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Set_Rahi_Stinger_Whale.jpg 1810w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/toa_undersea_attack.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"211\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/toa_undersea_attack-300x211.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/toa_undersea_attack-300x211.png 300w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/toa_undersea_attack.png 382w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Unnamed_Sea_Rahi_4.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Unnamed_Sea_Rahi_4-300x250.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Unnamed_Sea_Rahi_4-300x250.png 300w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Unnamed_Sea_Rahi_4-768x639.png 768w, https:\/\/biomediaproject.com\/bmp\/wp-content\/uploads\/2020\/12\/Unnamed_Sea_Rahi_4.png 985w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<ul>\n<li><a href=\"https:\/\/biomediaproject.com\/bmp\/files\/gfx\/1.0\/Advance%20Art\/2007\/Sets\/Playsets\/Toa%20Undersea%20Attack\/Alt%20Model\/Toa%20Undersea%20Attack%201.bmp\">BMP alt model<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>BMP alt model<\/p>\n","protected":false},"author":551,"featured_media":0,"parent":13568,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13584","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/13584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/users\/551"}],"replies":[{"embeddable":true,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/comments?post=13584"}],"version-history":[{"count":1,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/13584\/revisions"}],"predecessor-version":[{"id":13590,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/13584\/revisions\/13590"}],"up":[{"embeddable":true,"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/pages\/13568"}],"wp:attachment":[{"href":"https:\/\/biomediaproject.com\/bmp\/wp-json\/wp\/v2\/media?parent=13584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}